{"id":1367,"date":"2024-03-28T10:28:01","date_gmt":"2024-03-28T15:28:01","guid":{"rendered":"https:\/\/miami.antares.edu\/takvim\/"},"modified":"2024-08-03T23:09:36","modified_gmt":"2024-08-04T04:09:36","slug":"takvim","status":"publish","type":"page","link":"https:\/\/miami.antares.edu\/tr\/takvim\/","title":{"rendered":"Takvim"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; next_background_color=&#8221;#ffffff&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; background_image=&#8221;https:\/\/miami.antares.edu\/wp-content\/uploads\/2024\/02\/section-bg3.jpg&#8221; custom_padding=&#8221;75px||150px||false|false&#8221; custom_padding_tablet=&#8221;75px||150px||false|false&#8221; custom_padding_phone=&#8221;||125px||false|false&#8221; bottom_divider_style=&#8221;wave2&#8243; bottom_divider_height=&#8221;105px&#8221; bottom_divider_flip=&#8221;horizontal&#8221; custom_css_main_element=&#8221;border-image-slice: 1 !important;||border-top: 8px solid;||border-image-source: linear-gradient(90deg,#0577bf 0%,#cd3e45 100%) !important;&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;|700|||||||&#8221; header_text_color=&#8221;#333333&#8243; header_font_size=&#8221;51px&#8221; header_letter_spacing=&#8221;-2px&#8221; header_3_font=&#8221;||||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; positioning=&#8221;relative&#8221; module_alignment=&#8221;left&#8221; custom_margin=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>\ud83d\udccdOrlando<\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;|700|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;53px&#8221; header_letter_spacing=&#8221;-2px&#8221; header_text_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><span>Takvim<\/span><\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;-20px|||||&#8221; text_text_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span>D\u00f6nem ba\u015flang\u0131\u00e7 ve biti\u015f tarihleri, s\u0131nav programlar\u0131, tatiller ve Antares toplulu\u011fu taraf\u0131ndan d\u00fczenlenen \u00f6zel etkinlikler hakk\u0131nda bilgi sahibi olun.<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/miami.antares.edu\/wp-content\/uploads\/2024\/05\/academic-terms-calendar.jpg&#8221; title_text=&#8221;akademik-terimler-takvimi&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_image src=&#8221;https:\/\/miami.antares.edu\/wp-content\/uploads\/2024\/05\/intensive-english-calendar.jpg&#8221; title_text=&#8221;yo\u011fun-ingilizce-takvim&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; prev_background_color=&#8221;#f9f9f9&#8243; next_background_color=&#8221;#ffffff&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/miami.antares.edu\/wp-content\/uploads\/2024\/02\/section-bg2.jpg&#8221; parallax=&#8221;on&#8221; custom_padding=&#8221;100px||75px||false|false&#8221; custom_padding_tablet=&#8221;50px||50px||false|false&#8221; custom_padding_phone=&#8221;50px||50px||false|false&#8221; top_divider_style=&#8221;triangle&#8221; top_divider_height=&#8221;30px&#8221; bottom_divider_style=&#8221;triangle&#8221; bottom_divider_height=&#8221;30px&#8221; global_module=&#8221;1283&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.24.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;|700|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;45px&#8221; header_letter_spacing=&#8221;-1px&#8221; header_2_font=&#8221;|700|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;30px&#8221; header_2_letter_spacing=&#8221;-1px&#8221; header_4_font=&#8221;|600||on|||||&#8221; header_4_text_color=&#8221;#FFFFFF&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_5_font=&#8221;|||on|||||&#8221; header_5_text_color=&#8221;#ffffff&#8221; header_5_letter_spacing=&#8221;2px&#8221; max_width=&#8221;980px&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;0px||||false|false&#8221; header_text_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h5 style=\"text-align: center;\">\u00d6\u011frenmeye Ba\u015flay\u0131n<\/h5>\n<h1 style=\"text-align: center;\"><span>Hayat\u0131n\u0131z\u0131 Bug\u00fcn De\u011fi\u015ftirin<\/span><\/h1>\n<p style=\"text-align: center;\"><span>\u0130ster d\u00fcnyay\u0131 ke\u015ffetmeyi, ister bir ABD \u00fcniversitesine gitmeyi ya da i\u015f d\u00fcnyas\u0131nda m\u00fckemmelle\u015fmeyi hayal edin, programlar\u0131m\u0131z ba\u015far\u0131ya giden yolunuzdur.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjE5In19@&#8221; button_text=&#8221;\u015eimdi ba\u015fvurun&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.27.0&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_bg_color=&#8221;#CD3E45&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udccdOrlandoTakvimD\u00f6nem ba\u015flang\u0131\u00e7 ve biti\u015f tarihleri, s\u0131nav programlar\u0131, tatiller ve Antares toplulu\u011fu taraf\u0131ndan d\u00fczenlenen \u00f6zel etkinlikler hakk\u0131nda bilgi sahibi olun.\u00d6\u011frenmeye Ba\u015flay\u0131n Hayat\u0131n\u0131z\u0131 Bug\u00fcn De\u011fi\u015ftirin \u0130ster d\u00fcnyay\u0131 ke\u015ffetmeyi, ister bir ABD \u00fcniversitesine gitmeyi ya da i\u015f d\u00fcnyas\u0131nda m\u00fckemmelle\u015fmeyi hayal edin, programlar\u0131m\u0131z ba\u015far\u0131ya giden yolunuzdur.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1367","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Takvim - Antares Miami<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/miami.antares.edu\/tr\/takvim\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Takvim - Antares Miami\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udccdOrlandoTakvimD\u00f6nem ba\u015flang\u0131\u00e7 ve biti\u015f tarihleri, s\u0131nav programlar\u0131, tatiller ve Antares toplulu\u011fu taraf\u0131ndan d\u00fczenlenen \u00f6zel etkinlikler hakk\u0131nda bilgi sahibi olun.\u00d6\u011frenmeye Ba\u015flay\u0131n Hayat\u0131n\u0131z\u0131 Bug\u00fcn De\u011fi\u015ftirin \u0130ster d\u00fcnyay\u0131 ke\u015ffetmeyi, ister bir ABD \u00fcniversitesine gitmeyi ya da i\u015f d\u00fcnyas\u0131nda m\u00fckemmelle\u015fmeyi hayal edin, programlar\u0131m\u0131z ba\u015far\u0131ya giden yolunuzdur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/miami.antares.edu\/tr\/takvim\/\" \/>\n<meta property=\"og:site_name\" content=\"Antares Miami\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-04T04:09:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/takvim\\\/\",\"url\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/takvim\\\/\",\"name\":\"Takvim - Antares Miami\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/#website\"},\"datePublished\":\"2024-03-28T15:28:01+00:00\",\"dateModified\":\"2024-08-04T04:09:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/takvim\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/takvim\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/takvim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Takvim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/#website\",\"url\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/\",\"name\":\"Antares Orlando\",\"description\":\"Igniting Minds, Cultivating English Fluency in the Sunshine State!\",\"publisher\":{\"@id\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/#organization\",\"name\":\"Antares Orlando\",\"url\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/miami.antares.edu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/antares-logo.png\",\"contentUrl\":\"https:\\\/\\\/miami.antares.edu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/antares-logo.png\",\"width\":350,\"height\":130,\"caption\":\"Antares Orlando\"},\"image\":{\"@id\":\"https:\\\/\\\/miami.antares.edu\\\/tr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Takvim - Antares Miami","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/miami.antares.edu\/tr\/takvim\/","og_locale":"tr_TR","og_type":"article","og_title":"Takvim - Antares Miami","og_description":"\ud83d\udccdOrlandoTakvimD\u00f6nem ba\u015flang\u0131\u00e7 ve biti\u015f tarihleri, s\u0131nav programlar\u0131, tatiller ve Antares toplulu\u011fu taraf\u0131ndan d\u00fczenlenen \u00f6zel etkinlikler hakk\u0131nda bilgi sahibi olun.\u00d6\u011frenmeye Ba\u015flay\u0131n Hayat\u0131n\u0131z\u0131 Bug\u00fcn De\u011fi\u015ftirin \u0130ster d\u00fcnyay\u0131 ke\u015ffetmeyi, ister bir ABD \u00fcniversitesine gitmeyi ya da i\u015f d\u00fcnyas\u0131nda m\u00fckemmelle\u015fmeyi hayal edin, programlar\u0131m\u0131z ba\u015far\u0131ya giden yolunuzdur.","og_url":"https:\/\/miami.antares.edu\/tr\/takvim\/","og_site_name":"Antares Miami","article_modified_time":"2024-08-04T04:09:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tahmini okuma s\u00fcresi":"3 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/miami.antares.edu\/tr\/takvim\/","url":"https:\/\/miami.antares.edu\/tr\/takvim\/","name":"Takvim - Antares Miami","isPartOf":{"@id":"https:\/\/miami.antares.edu\/tr\/#website"},"datePublished":"2024-03-28T15:28:01+00:00","dateModified":"2024-08-04T04:09:36+00:00","breadcrumb":{"@id":"https:\/\/miami.antares.edu\/tr\/takvim\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/miami.antares.edu\/tr\/takvim\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/miami.antares.edu\/tr\/takvim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/miami.antares.edu\/tr\/"},{"@type":"ListItem","position":2,"name":"Takvim"}]},{"@type":"WebSite","@id":"https:\/\/miami.antares.edu\/tr\/#website","url":"https:\/\/miami.antares.edu\/tr\/","name":"Antares Orlando","description":"Igniting Minds, Cultivating English Fluency in the Sunshine State!","publisher":{"@id":"https:\/\/miami.antares.edu\/tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/miami.antares.edu\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"},{"@type":"Organization","@id":"https:\/\/miami.antares.edu\/tr\/#organization","name":"Antares Orlando","url":"https:\/\/miami.antares.edu\/tr\/","logo":{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/miami.antares.edu\/tr\/#\/schema\/logo\/image\/","url":"https:\/\/miami.antares.edu\/wp-content\/uploads\/2026\/01\/antares-logo.png","contentUrl":"https:\/\/miami.antares.edu\/wp-content\/uploads\/2026\/01\/antares-logo.png","width":350,"height":130,"caption":"Antares Orlando"},"image":{"@id":"https:\/\/miami.antares.edu\/tr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/miami.antares.edu\/tr\/wp-json\/wp\/v2\/pages\/1367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/miami.antares.edu\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/miami.antares.edu\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/miami.antares.edu\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/miami.antares.edu\/tr\/wp-json\/wp\/v2\/comments?post=1367"}],"version-history":[{"count":0,"href":"https:\/\/miami.antares.edu\/tr\/wp-json\/wp\/v2\/pages\/1367\/revisions"}],"wp:attachment":[{"href":"https:\/\/miami.antares.edu\/tr\/wp-json\/wp\/v2\/media?parent=1367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}